{"id":544,"date":"2020-03-06T01:05:51","date_gmt":"2020-03-06T00:05:51","guid":{"rendered":"https:\/\/loftybot.net\/?page_id=544"},"modified":"2026-03-23T21:03:52","modified_gmt":"2026-03-23T20:03:52","slug":"downloads","status":"publish","type":"page","link":"https:\/\/loftybot.net\/pt\/downloads\/","title":{"rendered":"Transfer\u00eancias"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"544\" class=\"elementor elementor-544\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"aux-parallax-section elementor-element elementor-element-4a0607e e-con-full e-flex e-con e-parent\" data-id=\"4a0607e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6f3348de e-con-full e-flex e-con e-child\" data-id=\"6f3348de\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f31cfa elementor-widget elementor-widget-heading\" data-id=\"1f31cfa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DOWNLOADS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbe9ff8 elementor-widget elementor-widget-aux_modern_heading\" data-id=\"cbe9ff8\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\">Atualiza\u00e7\u00f5es e registros de mudan\u00e7as<\/h2><\/div>\n        <\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a63dd5 elementor-button-success elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8a63dd5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"\/pt\/downloads-center\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cloud-download-alt\" viewbox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M537.6 226.6c4.1-10.7 6.4-22.4 6.4-34.6 0-53-43-96-96-96-19.7 0-38.1 6-53.3 16.2C367 64.2 315.3 32 256 32c-88.4 0-160 71.6-160 160 0 2.7.1 5.4.2 8.1C40.2 219.8 0 273.2 0 336c0 79.5 64.5 144 144 144h368c70.7 0 128-57.3 128-128 0-61.9-44-113.6-102.4-125.4zm-132.9 88.7L299.3 420.7c-6.2 6.2-16.4 6.2-22.6 0L171.3 315.3c-10.1-10.1-2.9-27.3 11.3-27.3H248V176c0-8.8 7.2-16 16-16h48c8.8 0 16 7.2 16 16v112h65.4c14.2 0 21.4 17.2 11.3 27.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Central de downloads<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21deccde elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21deccde\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c48e15c\" data-id=\"c48e15c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f39e42 elementor-widget elementor-widget-breadcrumbs\" data-id=\"2f39e42\" data-element_type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav aria-label=\"Migalhas de p\u00e3o\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Casa<\/span><\/p><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71aa0f92 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71aa0f92\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52e0c45\" data-id=\"52e0c45\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d312664 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d312664\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-405fbb0\" data-id=\"405fbb0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6ff334 elementor-widget elementor-widget-heading\" data-id=\"b6ff334\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ATUALIZA\u00c7\u00c3O MAIS RECENTE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df3080e elementor-widget elementor-widget-aux_recent_posts_land_style\" data-id=\"df3080e\" data-element_type=\"widget\" data-widget_type=\"aux_recent_posts_land_style.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"widget-container aux-widget-recent-posts-land aux-parent-aud67826f2\"><div data-element-id=\"aud67826f2\" class=\"aux-blog-land-style aux-ajax-view\"><div class=\"aux-block post-6044\">\n                        <article class=\"aux-column-post-entry land-post-style post-6044 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-bot-2025 tag-bot-2026 tag-realera-nexorium tag-wearedragons\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-5-realera-nexorium-8-0-wearedragons\/\">\n                                            Atualiza\u00e7\u00e3o 2.7.5 | Realera Nexorium 8.0 - WeAreDragons                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-5-realera-nexorium-8-0-wearedragons\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-5-realera-nexorium-8-0-wearedragons\/\">\n                                            <time datetime=\"2026-03-07T01:00:28+01:00\" title=\"2026-03-07T01:00:28+01:00\" >7 de mar\u00e7o de 2026<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                                                                                        <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>LoftyBot Melhor Bot de Tibia de 2026\n\t\tH\u00e1 muitas OTS novas no in\u00edcio do ano de 2026. A maioria dos servidores tem gr\u00e1ficos e visuais semelhantes. Isso significa que esses ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-5-realera-nexorium-8-0-wearedragons\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-5-realera-nexorium-8-0-wearedragons\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">3<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><\/div><\/section><!-- widget-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-372bef9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"372bef9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6ae09fc\" data-id=\"6ae09fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e9b139 elementor-widget elementor-widget-heading\" data-id=\"7e9b139\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">ATUALIZA\u00c7\u00d5ES ANTIGOS<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60f3458 elementor-widget elementor-widget-aux_recent_posts_land_style\" data-id=\"60f3458\" data-element_type=\"widget\" data-widget_type=\"aux_recent_posts_land_style.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>auxinNS(\"auxin.content.loadmore.au6b46c534\"); auxin.content.loadmore.au6b46c534={\"nonce\":\"8a62f15a2f\",\"args\":{\"title\":\"\",\"cat\":[\"12\"],\"num\":14,\"only_posts__in\":\"\",\"include\":\"\",\"exclude\":\"\",\"posts_per_page\":-1,\"paged\":\"\",\"offset\":1,\"order_by\":\"date\",\"order\":\"DESC\",\"size\":\"\",\"exclude_without_media\":\"no\",\"exclude_custom_post_formats\":\"no\",\"exclude_quote_link\":null,\"exclude_post_formats_in\":[],\"show_media\":\"\",\"show_excerpt\":\"yes\",\"show_content\":true,\"excerpt_len\":\"160\",\"excerpt_length\":\"\",\"display_title\":\"yes\",\"display_like\":\"yes\",\"display_comments\":\"yes\",\"display_categories\":\"yes\",\"max_taxonomy_num\":\"1\",\"show_info\":\"yes\",\"show_date\":\"yes\",\"author_or_readmore\":\"readmore\",\"display_author_footer\":null,\"display_author_header\":\"yes\",\"image_aspect_ratio\":null,\"tag\":\"\",\"taxonomy_name\":\"category\",\"preloadable\":null,\"preload_preview\":null,\"preload_bgcolor\":null,\"extra_classes\":\"\",\"extra_column_classes\":\"\",\"custom_el_id\":\"\",\"template_part_file\":\"theme-parts\\\/entry\\\/post-column\",\"extra_template_path\":\"\",\"universal_id\":\"au6b46c534\",\"reset_query\":true,\"wp_query_args\":[],\"loadmore_type\":\"next\",\"loadmore_per_page\":14,\"content\":null,\"skip_wrappers\":true,\"content_width\":2000,\"inview_transition\":\"none\",\"inview_duration\":\"\",\"inview_delay\":\"\",\"inview_repeat\":\"no\",\"inview_offset\":\"\",\"called_from\":\"\"},\"handler\":\"aux_recent_posts_land_style\",\"per_page\":14};<\/script><section class=\"widget-container aux-ajax-type-next aux-widget-recent-posts-land aux-parent-au6b46c534\"><div data-element-id=\"au6b46c534\" class=\"aux-blog-land-style aux-ajax-view\"><div class=\"aux-block aux-ajax-item post-5835\">\n                        <article class=\"aux-column-post-entry land-post-style post-5835 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-bot-2025 tag-castabra tag-exordion-bot tag-fibula tag-fibula-project tag-malvera tag-midheim tag-realera\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-4-project-fibula-malvera\/\">\n                                            Atualiza\u00e7\u00e3o 2.7.4 | Projeto Fibula - Malvera                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-4-project-fibula-malvera\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-4-project-fibula-malvera\/\">\n                                            <time datetime=\"2025-12-20T00:57:56+01:00\" title=\"2025-12-20T00:57:56+01:00\" >20 de dezembro de 2025<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                    <span class=\"entry-tax\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/category\/downloads\/\" title=\"Ver todas as postagens em Downloads\" rel=\"category\" >Transfer\u00eancias<\/a>                                    <\/span>\n                                                                                                                                            <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>LoftyBot Melhor Bot do Tibia de 2025\n\t\tNovos suportes de servidor adicionados!\nO LoftyBot agora funciona com estes servidores.\n\n \n- Projeto Fibula (https:\/\/www.projectfibula.com http ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-4-project-fibula-malvera\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-4-project-fibula-malvera\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">2<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><div class=\"aux-block aux-ajax-item post-5707\">\n                        <article class=\"aux-column-post-entry land-post-style post-5707 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-bot-2024 tag-bot-2025 tag-castabra tag-exordion-bot tag-midheim tag-realera\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-3-realera-arcentis-8-0\/\">\n                                            Atualiza\u00e7\u00e3o 2.7.3 | Realera Arcentis 8.0                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-3-realera-arcentis-8-0\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-3-realera-arcentis-8-0\/\">\n                                            <time datetime=\"2025-10-18T23:46:25+02:00\" title=\"2025-10-18T23:46:25+02:00\" >18 de outubro de 2025<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                    <span class=\"entry-tax\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/category\/downloads\/\" title=\"Ver todas as postagens em Downloads\" rel=\"category\" >Transfer\u00eancias<\/a>                                    <\/span>\n                                                                                                                                            <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>Atualiza\u00e7\u00e3o do LoftyBot - Estamos de volta! em 2025\n\t\tDepois de uma pequena pausa, estamos de volta ao jogo!\nO LoftyBot est\u00e1 sendo atualizado e ser\u00e1 mantido continuamente at\u00e9 ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-3-realera-arcentis-8-0\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-3-realera-arcentis-8-0\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">3<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><div class=\"aux-block aux-ajax-item post-4642\">\n                        <article class=\"aux-column-post-entry land-post-style post-4642 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-bot-2024 tag-bot-2025 tag-dura-online tag-shadow-illusion tag-tibia-bot-2025\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-2-treasura-dura-online\/\">\n                                            Atualiza\u00e7\u00e3o 2.7.2 | Treasura - Dura-online                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-2-treasura-dura-online\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-2-treasura-dura-online\/\">\n                                            <time datetime=\"2024-12-18T22:21:32+01:00\" title=\"2024-12-18T22:21:32+01:00\" >18 de dezembro de 2024<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                    <span class=\"entry-tax\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/category\/downloads\/\" title=\"Ver todas as postagens em Downloads\" rel=\"category\" >Transfer\u00eancias<\/a>                                    <\/span>\n                                                                                                                                            <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>Adicionada compatibilidade com os clientes OTS do Tibia:\n\t\t- Treasura.online (clique no bot\u00e3o Soul of Elysium)- Miracle74 OTS miracle74.com (bot\u00e3o Kasteria)- Shadow-illusion ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-2-treasura-dura-online\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-2-treasura-dura-online\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">4<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><div class=\"aux-block aux-ajax-item post-4571\">\n                        <article class=\"aux-column-post-entry land-post-style post-4571 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-bot-2024 tag-iglaots tag-miracle74 tag-ots tag-tibia-bot\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-1-miracle74-iglaots\/\">\n                                            Atualiza\u00e7\u00e3o 2.7.1 | Miracle74 - IglaOTS                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-1-miracle74-iglaots\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-1-miracle74-iglaots\/\">\n                                            <time datetime=\"2024-10-07T14:36:42+02:00\" title=\"2024-10-07T14:36:42+02:00\" >7 de outubro de 2024<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                    <span class=\"entry-tax\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/category\/downloads\/\" title=\"Ver todas as postagens em Downloads\" rel=\"category\" >Transfer\u00eancias<\/a>                                    <\/span>\n                                                                                                                                            <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>Atualiza\u00e7\u00e3o do LoftyBot Bot Tibia 2024\nAdicionado suporte a novos OTS e clientes:\n- IglaOTS (bot\u00e3o Novo Tibia)- Miracle74 OTS miracle74.com (bot\u00e3o Kasteria)- Tibiantis chec ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-1-miracle74-iglaots\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-1-miracle74-iglaots\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">10<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><div class=\"aux-block aux-ajax-item post-4530\">\n                        <article class=\"aux-column-post-entry land-post-style post-4530 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-8-0-tibia-bot tag-dbvictory tag-realera\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-0-realera-dbvictory-2024\/\">\n                                            Atualiza\u00e7\u00e3o 2.7.0 | Realera - DBVictory - 2024                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-0-realera-dbvictory-2024\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-0-realera-dbvictory-2024\/\">\n                                            <time datetime=\"2024-02-16T17:16:47+01:00\" title=\"2024-02-16T17:16:47+01:00\" >16 de fevereiro de 2024<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                    <span class=\"entry-tax\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/category\/downloads\/\" title=\"Ver todas as postagens em Downloads\" rel=\"category\" >Transfer\u00eancias<\/a>                                    <\/span>\n                                                                                                                                            <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>Atualiza\u00e7\u00e3o do LoftyBot Bot Tibia\nVers\u00e3o 2.7.0\nAdicionado suporte a novas OTS e clientes:\n- Verificado Giveria.com ainda est\u00e1 funcionando (algumas pessoas relataram que n\u00e3o funcionou. Lembrem-se ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-0-realera-dbvictory-2024\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-7-0-realera-dbvictory-2024\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">8<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><div class=\"aux-block aux-ajax-item post-4486\">\n                        <article class=\"aux-column-post-entry land-post-style post-4486 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-kasteria tag-midheim-bot tag-nostalrius tag-tibia-bot\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-9-nostalrius-kasteria-midheim\/\">\n                                            Atualiza\u00e7\u00e3o 2.6.9 | Nostalrius - Kasteria - Midheim                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-9-nostalrius-kasteria-midheim\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-9-nostalrius-kasteria-midheim\/\">\n                                            <time datetime=\"2024-01-10T17:54:15+01:00\" title=\"2024-01-10T17:54:15+01:00\" >10 de janeiro de 2024<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                    <span class=\"entry-tax\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/category\/downloads\/\" title=\"Ver todas as postagens em Downloads\" rel=\"category\" >Transfer\u00eancias<\/a>                                    <\/span>\n                                                                                                                                            <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>Atualiza\u00e7\u00e3o do LoftyBot Bot Tibia\nVers\u00e3o 2.6.9 - Bem-vindo ao ano de 2024 Bots\nAdicionado suporte a novos OTS e clientes:\n- Midheim.online- Kasteria.online- Nostalrius.com.br\n ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-9-nostalrius-kasteria-midheim\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-9-nostalrius-kasteria-midheim\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">0<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><div class=\"aux-block aux-ajax-item post-4380\">\n                        <article class=\"aux-column-post-entry land-post-style post-4380 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-antiga-online tag-bot-2023 tag-castabra-ots tag-soul-of-elysium tag-tibia-bot\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-8-castabra-souls-of-elysium-antiga\/\">\n                                            Atualiza\u00e7\u00e3o 2.6.8 | Castabra - Souls of Elysium - Antiga                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-8-castabra-souls-of-elysium-antiga\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-8-castabra-souls-of-elysium-antiga\/\">\n                                            <time datetime=\"2023-10-27T21:01:17+02:00\" title=\"2023-10-27T21:01:17+02:00\" >27 de outubro de 2023<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                    <span class=\"entry-tax\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/category\/downloads\/\" title=\"Ver todas as postagens em Downloads\" rel=\"category\" >Transfer\u00eancias<\/a>                                    <\/span>\n                                                                                                                                            <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>Atualiza\u00e7\u00e3o do LoftyBot Bot Tibia\n2.6.8 Vers\u00e3o 2023\nNovos clientes suportados OTS e corre\u00e7\u00f5es:\n- Suporta Antiga.online- Suporta Souls of Elysium - eu.soerpg.com- Suporta ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-8-castabra-souls-of-elysium-antiga\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-8-castabra-souls-of-elysium-antiga\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">1<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><div class=\"aux-block aux-ajax-item post-3193\">\n                        <article class=\"aux-column-post-entry land-post-style post-3193 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-8-0-tibia-bot tag-bot-2021-tibia tag-bot-2023 tag-bot-shadow-ilussion tag-bot-tibia-shadowillusion tag-retrocores-bot tag-tibiantis-bot\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-7-shadowillusion-retrocores-tibiantis\/\">\n                                            Atualiza\u00e7\u00e3o 2.6.7 | ShadowIllusion - RetroCores - Tibiantis                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-7-shadowillusion-retrocores-tibiantis\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-7-shadowillusion-retrocores-tibiantis\/\">\n                                            <time datetime=\"2023-10-01T22:52:08+02:00\" title=\"2023-10-01T22:52:08+02:00\" >1 de outubro de 2023<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                    <span class=\"entry-tax\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/category\/downloads\/\" title=\"Ver todas as postagens em Downloads\" rel=\"category\" >Transfer\u00eancias<\/a>                                    <\/span>\n                                                                                                                                            <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>Atualiza\u00e7\u00e3o do LoftyBot Bot Tibia\n2.6.7 Vers\u00e3o 2023\nNovos clientes suportados OTS e corre\u00e7\u00f5es:\n- Adicionada compatibilidade com ShadowIlussion e RetroCores OTS- Funciona no Tibiant ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-7-shadowillusion-retrocores-tibiantis\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-7-shadowillusion-retrocores-tibiantis\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">0<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><div class=\"aux-block aux-ajax-item post-3177\">\n                        <article class=\"aux-column-post-entry land-post-style post-3177 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-8-0-tibia-bot tag-bot-2021-tibia tag-bot-2023-tibia tag-realera tag-realera-bot tag-tibia-realera-8-0\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-6-realera-bot-2023\/\">\n                                            Atualiza\u00e7\u00e3o 2.6.6 | Realera - Bot 2023                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-6-realera-bot-2023\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-6-realera-bot-2023\/\">\n                                            <time datetime=\"2023-09-20T09:08:23+02:00\" title=\"2023-09-20T09:08:23+02:00\" >20 de setembro de 2023<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                    <span class=\"entry-tax\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/category\/downloads\/\" title=\"Ver todas as postagens em Downloads\" rel=\"category\" >Transfer\u00eancias<\/a>                                    <\/span>\n                                                                                                                                            <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>Atualiza\u00e7\u00e3o do LoftyBot Bot Tibia\nNovos clientes suportados OTS e corre\u00e7\u00f5es:\n- Melhoria do walker - Melhoria da GUI e da janela de \u00faltimas mensagens - Compatibilidade adicionada com o mais novo cliente realera ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-6-realera-bot-2023\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-6-realera-bot-2023\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">2<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><div class=\"aux-block aux-ajax-item post-3030\">\n                        <article class=\"aux-column-post-entry land-post-style post-3030 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-bot-2021-tibia tag-bot-2023-tibia tag-gunzodus-bot tag-imperianic-ots tag-medivia tag-nostalher tag-nostalrius tag-nostalrius-ots tag-realesta tag-realesta-bot tag-tibia-bot tag-tibia-bot-12 tag-tibia-bot-2020 tag-tibia-bot-2021 tag-tibia-bot-7-4 tag-tibia-old tag-tibia-old-bot tag-wearedragons\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-5-olders-medivia-nostalher\/\">\n                                            Atualiza\u00e7\u00e3o 2.6.5 | Antigos - Medivia - Nostalher                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-5-olders-medivia-nostalher\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-5-olders-medivia-nostalher\/\">\n                                            <time datetime=\"2023-07-17T03:07:49+02:00\" title=\"2023-07-17T03:07:49+02:00\" >17 de julho de 2023<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                    <span class=\"entry-tax\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/category\/downloads\/\" title=\"Ver todas as postagens em Downloads\" rel=\"category\" >Transfer\u00eancias<\/a>                                    <\/span>\n                                                                                                                                            <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>Atualiza\u00e7\u00e3o do LoftyBot 2023 Bot Tibia OTS\nNovos clientes suportados OTS e corre\u00e7\u00f5es:\n- Medivia nova compatibilidade ajustada- Olders.online 8.0- Nostalther- Wearedragons- Reale ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-5-olders-medivia-nostalher\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-5-olders-medivia-nostalher\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">1<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><div class=\"aux-block aux-ajax-item post-2899\">\n                        <article class=\"aux-column-post-entry land-post-style post-2899 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-bot-2021-tibia tag-givera-ots tag-gunzodus-bot tag-imperianic-ots tag-kasteria-ots tag-kingdomswap tag-nostalrius tag-nostalrius-ots tag-ramonia-pl-bot tag-realesta-bot tag-tibia-bot tag-tibia-bot-12 tag-tibia-bot-2020 tag-tibia-bot-2021 tag-tibia-bot-7-4 tag-tibia-old tag-tibia-old-bot\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/nostalrius-ezodus-ramonia-bot\/\">\n                                            Atualiza\u00e7\u00e3o 2.6.4 | Nostalrius - Ezodus - Ramonia - Tibiantis                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/nostalrius-ezodus-ramonia-bot\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/nostalrius-ezodus-ramonia-bot\/\">\n                                            <time datetime=\"2022-01-20T03:48:01+01:00\" title=\"2022-01-20T03:48:01+01:00\" >20 janeiro 2022<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                    <span class=\"entry-tax\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/category\/downloads\/\" title=\"Ver todas as postagens em Downloads\" rel=\"category\" >Transfer\u00eancias<\/a>                                    <\/span>\n                                                                                                                                            <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>Atualiza\u00e7\u00e3o do LoftyBot 2022 para todos os OTS de Tibia\nNovos clientes apoiados OTS e consertos:\n- Medivia novo cliente fixo - Tibiantis novo 1,50 - Nostolrius novo cliente fixo - Ezodus ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/nostalrius-ezodus-ramonia-bot\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/nostalrius-ezodus-ramonia-bot\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">28<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><div class=\"aux-block aux-ajax-item post-2825\">\n                        <article class=\"aux-column-post-entry land-post-style post-2825 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-bot-2021-tibia tag-ezodus-net-bot tag-givera-ots tag-gunzodus-bot tag-imperianic-ots tag-ixodus tag-kasteria-ots tag-kingdomswap tag-midheim-com tag-nostalrius tag-nostalrius-ots tag-ramonia-pl-bot tag-realesta-bot tag-tibia-bot tag-tibia-bot-12 tag-tibia-bot-2020 tag-tibia-bot-2021 tag-tibia-bot-7-4 tag-tibia-old tag-tibia-old-bot tag-visionot tag-wearedragons\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-kingdomswap-wearedragons-ixodus\/\">\n                                            Atualiza\u00e7\u00e3o 2.6.3 | KingdomSwap - WeAreDragons - Ixodus                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-kingdomswap-wearedragons-ixodus\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-kingdomswap-wearedragons-ixodus\/\">\n                                            <time datetime=\"2021-10-09T02:01:41+02:00\" title=\"2021-10-09T02: 01: 41 + 02: 00\" >9 de outubro de 2021<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                    <span class=\"entry-tax\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/category\/downloads\/\" title=\"Ver todas as postagens em Downloads\" rel=\"category\" >Transfer\u00eancias<\/a>                                    <\/span>\n                                                                                                                                            <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>Quase todos os OTS verificam quantos: Lista de suporte Novos clientes suportados OTS e corre\u00e7\u00f5es: - KingdomSwap https:\/\/kingdom-swap.com\/- VisionOT - tibia-old.com- Medivi ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-kingdomswap-wearedragons-ixodus\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-kingdomswap-wearedragons-ixodus\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">31<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><div class=\"aux-block aux-ajax-item post-2729\">\n                        <article class=\"aux-column-post-entry land-post-style post-2729 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-bot-2021-tibia tag-ezodus-net-bot tag-givera-ots tag-gunzodus-bot tag-imperianic-ots tag-kasteria-ots tag-midheim-com tag-nostalrius tag-nostalrius-ots tag-ramonia-pl-bot tag-realesta-bot tag-tibia-bot tag-tibia-bot-12 tag-tibia-bot-2020 tag-tibia-bot-2021 tag-tibia-bot-7-4 tag-tibia-old-bot tag-visionot\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-2-imperianic-visionot-rots\/\">\n                                            Atualiza\u00e7\u00e3o 2.6.2 | Imperianic - VisionOT - ROTS                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-2-imperianic-visionot-rots\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-2-imperianic-visionot-rots\/\">\n                                            <time datetime=\"2021-07-22T22:08:51+02:00\" title=\"2021-07-22T22: 08: 51 + 02: 00\" >22 de julho de 2021<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                    <span class=\"entry-tax\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/category\/downloads\/\" title=\"Ver todas as postagens em Downloads\" rel=\"category\" >Transfer\u00eancias<\/a>                                    <\/span>\n                                                                                                                                            <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>\r\n\r\n\r\n\r\nQuase todos os OTS verificam quantos: Lista de suporte Novos clientes suportados OTS e corre\u00e7\u00f5es: - ROTS detectando v\u00e1rios caracteres corrigidos. Treinamento ROTS aprimorado - C ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-2-imperianic-visionot-rots\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-2-imperianic-visionot-rots\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">14<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><div class=\"aux-block aux-ajax-item post-2411\">\n                        <article class=\"aux-column-post-entry land-post-style post-2411 post type-post status-publish format-standard has-post-thumbnail hentry category-downloads tag-bot-2021-tibia tag-ezodus-net-bot tag-imperianic-ots tag-kasteria-ots tag-nostalrius tag-nostalrius-ots tag-ramonia-pl-bot tag-realesta-bot tag-tibia-bot tag-tibia-bot-12 tag-tibia-bot-2020 tag-tibia-bot-2021 tag-tibia-bot-7-4 tag-tibia-old-bot\">\n                            \n                            <div class=\"entry-main\">\n                                                        \n                                <header class=\"entry-header\">\n                                \n                                    <h4 class=\"entry-title\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-1-ezodus-ramonia-tibia-old-bot\/\">\n                                            Atualiza\u00e7\u00e3o 2.6.1 | Ezodus - Ramonia - Tibia-old                                        <\/a>\n                                    <\/h4>\n                                                                    <div class=\"entry-format\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-1-ezodus-ramonia-tibia-old-bot\/\">\n                                            <div class=\"post-format format-\"> <\/div>\n                                        <\/a>\n                                    <\/div>\n                                <\/header>\n                                                            \n                                <div class=\"entry-info\">\n                                                                    <div class=\"entry-date\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-1-ezodus-ramonia-tibia-old-bot\/\">\n                                            <time datetime=\"2021-04-07T01:47:12+02:00\" title=\"2021-04-07T01: 47: 12 + 02: 00\" >7 de abril de 2021<\/time>\n                                        <\/a>\n                                    <\/div>\n                                                                                                    <span class=\"entry-meta-sep meta-sep\">de<\/span>\n                                    <span class=\"author vcard\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/author\/lofty\/\" rel=\"author\" title=\"Ver todas as postagens de Lofty Admin\" >\n                                            Lofty Admin                                        <\/a>\n                                    <\/span>\n                                                                                                    <span class=\"entry-tax\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/category\/downloads\/\" title=\"Ver todas as postagens em Downloads\" rel=\"category\" >Transfer\u00eancias<\/a>                                    <\/span>\n                                                                                                                                            <\/div>\n                            \n                                                            <div class=\"entry-content\">\n                                                                            <p>\r\n\r\n\r\n\r\nLoftyBot - 2021 Bot Tibia Quase todos os OTS Supports-list Novos clientes suportados: - Ramonia.plFixes para clientes suportados existentes: - Medivia.online- Ezod ...<\/p><div class=\"clear\"><\/div>                                <\/div>\n                                                                                        <footer class=\"entry-meta aux-after-content\">\n                                                                        <div class=\"readmore\">\n                                        <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-1-ezodus-ramonia-tibia-old-bot\/\" class=\"aux-read-more\"><span class=\"aux-read-more-text\">consulte Mais informa\u00e7\u00e3o<\/span><\/a>\n                                    <\/div>\n                                                                        <div class=\"comments-iconic\">\n                                                                                    <a href=\"https:\/\/loftybot.net\/pt\/downloads\/update-2-6-1-ezodus-ramonia-tibia-old-bot\/#comments\" class=\"meta-comment\" >\n                                                <span class=\"auxicon-comment\"><\/span><span class=\"comments-number\">7<\/span>\n                                            <\/a>\n                                                                            <\/div>\n                                                                    <\/footer>\n                            \n                            <\/div>\n\n                        <\/article>\n<\/div><\/div>\n        <div class=\"aux-ajax-controller\">\n            <nav class=\"aux-load-more center\">\n              <svg class=\"aux-circle\" width=\"100%\" height=\"100%\" viewbox=\"0 0 102 102\">\n                <circle class=\"aux-progress-bg\" r=\"50\" cx=\"51\" cy=\"51\" fill=\"none\" transform=\"rotate(-90 51 51)\"><\/circle>\n                <circle class=\"aux-progress\" r=\"50\" cx=\"51\" cy=\"51\" fill=\"none\" transform=\"rotate(-90 51 51)\"><\/circle>\n              <\/svg>\n              <div class=\"aux-label-text\">CARREGUE MAIS<\/div>\n              <span class=\"aux-loading-label\">CARREGANDO<\/span>\n            <\/nav>\n        <\/div><\/section><!-- widget-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>DOWNLOADS Updates and changelogs Downloads Center Home NEWEST UPDATE Update 2.7.5 | Realera Nexorium 8.0 - WeAreDragons 7 March 2026 by Lofty Admin | Edit LoftyBot Best Tibia Bot of 2026 H\u00e1 muitos OTS novos no in\u00edcio do ano de 2026. A maioria dos servidores tem gr\u00e1ficos e visuais semelhantes. Isso significa que esses ... [...]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-544","page","type-page","status-publish","hentry"],"meta_box":[],"_links":{"self":[{"href":"https:\/\/loftybot.net\/pt\/wp-json\/wp\/v2\/pages\/544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loftybot.net\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/loftybot.net\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/loftybot.net\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/loftybot.net\/pt\/wp-json\/wp\/v2\/comments?post=544"}],"version-history":[{"count":6,"href":"https:\/\/loftybot.net\/pt\/wp-json\/wp\/v2\/pages\/544\/revisions"}],"predecessor-version":[{"id":6060,"href":"https:\/\/loftybot.net\/pt\/wp-json\/wp\/v2\/pages\/544\/revisions\/6060"}],"wp:attachment":[{"href":"https:\/\/loftybot.net\/pt\/wp-json\/wp\/v2\/media?parent=544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}